
{"id":14692,"date":"2025-02-11T04:10:31","date_gmt":"2025-02-11T04:10:31","guid":{"rendered":"https:\/\/pbn3.go.th\/news\/?p=14692"},"modified":"2025-02-11T04:10:33","modified_gmt":"2025-02-11T04:10:33","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/pbn3.go.th\/news\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e43\u0e19\u0e40\u0e02\u0e15\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 17 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2568"},"content":{"rendered":"\n<p>\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e.\u0e28. 2568 \u0e40\u0e27\u0e25\u0e32 09.00 \u0e19. \u0e19\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e1a\u0e38\u0e0d\u0e40\u0e1e\u0e47\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e02\u0e15 3 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e04\u0e33\u0e1b\u0e38\u0e19 \u0e40\u0e2a\u0e19\u0e28\u0e23\u0e35 \u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e02\u0e15 3 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e43\u0e19\u0e40\u0e02\u0e15\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 17 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2568 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e34\u0e23\u0e34\u0e27\u0e23\u0e23\u0e13 \u0e02\u0e27\u0e31\u0e0d\u0e21\u0e38\u0e02 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e21\u0e35 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e17 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e17. \u0e17\u0e35\u0e48\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e2a\u0e1e\u0e10. \u0e43\u0e19\u0e40\u0e02\u0e15\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 17 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e02\u0e27\u0e31\u0e0d\u0e0a\u0e19\u0e01 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c<\/p>\n\n\n\nngg_shortcode_0_placeholder\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/share\/p\/15ey9dLVYN\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e.\u0e28. 2568 \u0e40\u0e27\u0e25\u0e32 09.00 \u0e19. \u0e19\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e1a\u0e38\u0e0d\u0e40\u0e1e\u0e47\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e02\u0e15 3 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e04\u0e33\u0e1b\u0e38\u0e19 \u0e40\u0e2a\u0e19\u0e28\u0e23\u0e35 \u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e02\u0e15 3 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e43\u0e19\u0e40\u0e02\u0e15\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 17 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2568 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e34\u0e23\u0e34\u0e27\u0e23\u0e23\u0e13 \u0e02\u0e27\u0e31\u0e0d\u0e21\u0e38\u0e02 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e21\u0e35 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e17 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e17. \u0e17\u0e35\u0e48\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e2a\u0e1e\u0e10. \u0e43\u0e19\u0e40\u0e02\u0e15\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 17 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e02\u0e27\u0e31\u0e0d\u0e0a\u0e19\u0e01 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c<\/p>\n","protected":false},"author":2,"featured_media":14703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-14692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity"],"_links":{"self":[{"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/posts\/14692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/comments?post=14692"}],"version-history":[{"count":1,"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/posts\/14692\/revisions"}],"predecessor-version":[{"id":14704,"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/posts\/14692\/revisions\/14704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/media\/14703"}],"wp:attachment":[{"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/media?parent=14692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/categories?post=14692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pbn3.go.th\/news\/wp-json\/wp\/v2\/tags?post=14692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}